{"id":6841,"date":"2026-01-25T23:30:00","date_gmt":"2026-01-25T22:30:00","guid":{"rendered":"https:\/\/bordeaux-echecs.fr\/?p=6841"},"modified":"2026-03-26T17:07:23","modified_gmt":"2026-03-26T16:07:23","slug":"interclubs-jeunes-2025-2026-janvier-bis","status":"publish","type":"post","link":"https:\/\/bordeaux-echecs.fr\/index.php\/interclubs-jeunes-2025-2026-janvier-bis\/","title":{"rendered":"Interclubs jeunes 2025-2026 Janvier bis"},"content":{"rendered":"\n<p>En route vers Nantes pour un gros week-end en <strong>Nationale 1 jeunes <\/strong>! L&rsquo;\u00e9quipe joue le samedi \u00e0 16h contre Nantes et le lendemain \u00e0 9h30 contre Rennes. Les adversaires sont forts et il va falloir beaucoup d&rsquo;\u00e9nergie! <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Le samedi, Nantes est effectivement costaud. A l&rsquo;\u00e9lo, ils semblent plus forts en U12, ce sera chaud en U14 et on est peut-\u00eatre mieux en U16. Le match va t-il encore se jouer gr\u00e2ce aux  poussins en U10 ? En tous cas, \u00e7a d\u00e9marre fort chez les plus jeunes, \u00c9milien joue tr\u00e8s bien et Pierre aussi. Les parties avancent mais au bout d&rsquo;une heure, rien n&rsquo;est fait. En U12, Camille a mang\u00e9 un pion mais le retard de d\u00e9veloppement va \u00eatre compliqu\u00e9 \u00e0 g\u00e9rer. A la moindre impr\u00e9cision, \u00e7a peut se payer. Sacha a une position correcte mais son adversaire en embuscade cherche l&rsquo;initiative. Sacha loupe la d\u00e9fense et au 17\u00e8me coup c&rsquo;est la petite boulette. Boum! Sa position explose et son adversaire ne va pas le louper! Martin est dans son \u00e9l\u00e9ment et sa partie promet. Tim a l&rsquo;air \u00e0 l&rsquo;attaque et en forme, Nouaym aussi. Quant \u00e0 Augustin, m\u00eame si son adversaire semble avoir \u00e9galis\u00e9, il est d&rsquo;un calme impressionnant!<br>Bon, \u00e7a avance en U10! \u00c9milien a trouv\u00e9 une forte id\u00e9e mais la n\u00e9gocie mal. On a peur un instant car il a laiss\u00e9 un pion en route&#8230; Mais son adversaire craque, rend le pion, lui ouvre les cases noires et \u00c9milien voit le trou! \u00c7a flotte un peu mais le mat arrive enfin! 1-0. Pendant ce temps Pierre est proche de gagner mais manque de temps; il loupe un gain facile et devra finir une finale avec juste un pion d&rsquo;avance. Avec moins de 50s \u00e0 la pendule, il est raisonnable de proposer une nulle qui est accept\u00e9e. Pause bien m\u00e9rit\u00e9e.<br>Plus haut, le ciel s&rsquo;assombrit (faut dire qu&rsquo;on a pris des trombes d&rsquo;eau tout le week-end :))&#8230; Si on a cru sur un coup que Sacha pouvait s&rsquo;en sortir, ce n&rsquo;est pas le cas, une ligne tactique tr\u00e8s jolie le condamne. Il va d\u00e9fendre mais pas de doute sur l&rsquo;issue cette fois. C&rsquo;est Tim et Nouaym qui inqui\u00e8tent maintenant le plus car leur avantage est moins clair.<br>Les poussins reprennent et comme souvent, c&rsquo;est un peu dur de s&rsquo;y remettre! Avec les noirs, Pierre tient le choc mais \u00c9milien a mal d\u00e9but\u00e9. On joue depuis plus de 2h et \u00e0 ce moment du match, on n&rsquo;est pas en forme. L&rsquo;adversaire de Camille a sacrifi\u00e9 une pi\u00e8ce et le pauvre ne peut presque plus bouger. Si \u00e7a fait nulle ce sera bien&#8230; On pense que les points vont s&rsquo;encha\u00eener pour Nantes. C&rsquo;est confirm\u00e9 pour Sacha mais \u00c9milien profite d&rsquo;une \u00e9norme gaffe et au lieu de perdre une pi\u00e8ce il gagne une qualit\u00e9, puis une tour, puis la partie! 2-2.<br>Comme Martin accro\u00eet la pression et gagne, peu importe que Camille \u00e9touffe&#8230; \u00c7a fera 4-4. C&rsquo;est \u00e0 ce moment que Pierre, rattrape le pion qu&rsquo;il venait juste de donner en finale de tours, il devrait sauver la nulle? Non? Oui ? Non? et Paf! son adversaire veut forcer le passage et oublie une enfilade qui lui co\u00fbte sa tour! Pierre gagne et 5-4. <br>Cela aurait pu \u00eatre bon mais non! Tim a craqu\u00e9. 5-6. Nous voil\u00e0 donc derri\u00e8re pour la premi\u00e8re fois de l&rsquo;apr\u00e8s midi. Restent Nouaym et Augustin au finish avec peu de temps \u00e0 la pendule. Tout est possible. En direct, on ne voit pas que Nouaym passe de gagnant \u00e0 perdant&#8230; Cela va trop vite. C&rsquo;est mieux pour le c\u0153ur. J&rsquo;ai juste le temps de prendre l&rsquo;air&#8230; Je reviens et Nounou profite d&rsquo;une nouvelle erreur! Cette fois l&rsquo;avantage est plus facile \u00e0 jouer. En grande difficult\u00e9, son adversaire oublie la pendule et perd au temps dans une position  probablement d\u00e9sesp\u00e9r\u00e9e mais pas si simple \u00e0 jouer. Ouf! 7-6. Bien s\u00fbr une nulle suffit \u00e0 Augustin pour faire gagner le match. \u00c7a va le faire puisque depuis un moment il joue une finale tour et bon cavalier contre tour et mauvais fou&#8230; \u00c7a \u00e9volue peut \u00eatre vers la nulle mais lui aussi, en zeitnot, a trouv\u00e9 un avantage plus grand. Le bougre va m\u00eame la gagner! 9-6. <br>Un magnifique match, tr\u00e8s serr\u00e9 o\u00f9 les deux \u00e9quipes auraient pu l&#8217;emporter mais un petit coup de pouce de notre bonne \u00e9toile et surtout encore un 3 sur 4 des poussins ont fait la diff. <\/p>\n\n\n\n<p>Repas resto, Miam&#8230; Dodo! <\/p>\n\n\n\n<p>Le lendemain, il faut un bon p&rsquo;tit d\u00e8j \u00e0 l&rsquo;h\u00f4tel car les yeux sont encore un peu ferm\u00e9s. Un signe? Les poussins ont l&rsquo;air d&rsquo;avoir bien dormi et Sacha, pas tr\u00e8s en forme la veille va mieux!<br>Mais le second match du week-end est toujours dur loin de chez soi. Rennes est un peu moins fort sur le papier mais la fatigue est dangereuse. <br>Le r\u00e9sum\u00e9 pr\u00e9cis du match est difficile \u00e0 faire car il y a eu de tr\u00e8s tr\u00e8s nombreux retournements de situation. En U10, d&rsquo;abord o\u00f9 les pi\u00e8ces ont vol\u00e9, une de moins pour Pierre, une de plus pour \u00c9milien, transform\u00e9e en &#8230; dame de moins. C&rsquo;est perdu mais son adversaire offre la nulle&#8230; Alors que Pierre r\u00e9cup\u00e8re sa pi\u00e8ce et prendra m\u00eame une tour! Le match retour est du m\u00eame acabit. Pierre gagne, puis perd puis oublie de mater et r\u00e9p\u00e8te finalement les coups dans une position gagnante. Pour \u00c9milien c&rsquo;est tr\u00e8s \u00e9gal mais les joueurs sont d&rsquo;accord pour trouver des complications dont \u00c9milien sort gagnant! 2-0 \u00e0 l&rsquo;arriv\u00e9e. <br>En U12 c&rsquo;est aussi la folie! Camille semble tout ma\u00eetriser depuis qu&rsquo;il a enferm\u00e9 une pi\u00e8ce ennemie. L\u00e0 il se fait clouer la dame &#8230; Sacha semblait gagnant et pouf, il laisse passer sa chance. Pire, en finale de pion il craque. Mais ces deux l\u00e0 ont 2 vies! Ils se remobilisent et r\u00e9ussissent \u00e0 saouler leurs adversaires. Camille fait suffisamment peur au sien qui pr\u00e9f\u00e8re r\u00e9p\u00e9ter les coups. Sacha sauve une finale de dame avec 3 pions de moins &#8230; 2 nulles et toujours 2-0.<br>Allons voir les U14, cela devrait \u00eatre plus calme. Martin a pris un bon pion de plus et tout est ok; Tim am\u00e9liore lentement mais s\u00fbrement une partie \u00e9gale. On pense un moment compter sur 2 victoires mais Martin perd le fil et doit m\u00eame se sauver en finale de fous de couleurs oppos\u00e9es. Et Tim n&rsquo;a plus beaucoup de temps, il est sans doute gagnant mais les rois s&rsquo;exposent et avec dames et cavaliers qui tournoient \u00e7a devient chaud&#8230; <br>Heureusement je peux me reposer en pistant les U16 ? Que nenni! Ils vont eux aussi d\u00e9penser beaucoup de temps et Augustin ira m\u00eame jusqu\u2019\u00e0 n&rsquo;avoir plus que 2s lorsque qu&rsquo;il fait tomber son fou et prend poliment le temps de ramasser les pi\u00e8ces avant d&rsquo;appuyer sur la pendule&#8230; <br>A l&rsquo;arriv\u00e9e, Martin fera nulle, Nouaym termine (4-0 et ouf) et tout finit bien puisque Tim trouve un mat (6-0) alors qu&rsquo;Augustin encore le dernier \u00e0 finir apr\u00e8s avoir jou\u00e9 35 coups sur l&rsquo;incr\u00e9ment va gagner sa finale de tour \u00e9gale!! 8-0. Le score est large mais que d&rsquo;\u00e9motions!<\/p>\n\n\n\n<p>5 matches, 5 victoires. La t\u00eate du groupe bien s\u00fbr et la premi\u00e8re mission du maintien est remplie. On est m\u00eame plut\u00f4t bien parti pour&#8230; Chut! Fin du championnat en avril avec les deux derni\u00e8res rondes \u00e0 Bordeaux!  Merci les parents accompagnateurs, un soutien qui vaut bien 22 sur 20 !<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-6e0b5d00     \"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--masonry spectra-image-gallery__layout--masonry-col-3 spectra-image-gallery__layout--masonry-col-tab-3 spectra-image-gallery__layout--masonry-col-mob-2\">\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6848' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_1.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_1.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_1-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6847' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_2.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_2.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_2-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6846' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_3.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_3.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_3-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6843' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_6.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_6.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_6-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6845' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_4.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_4.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_4-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper--isotope'>\n\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='6844' tabindex=\"0\">\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--masonry\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_5.jpg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" srcset=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_5.jpg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--masonry\" src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_5-225x300.jpg\" alt=\"\" loading=\"lazy\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__control-lightbox' tabindex='0'>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper spectra-image-gallery__control-lightbox--main\" dir=\"\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_1.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_2.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_3.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_6.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_4.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2026\/01\/N1_jeunes_01_2026_5.jpg\" alt=\"\"\/>\n\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader swiper-lazy-preloader-white\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<\/div>\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button class='spectra-image-gallery__control-lightbox--close' aria-label=\"Close\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 320 512\"><path d=\"M310.6 361.4c12.5 12.5 12.5 32.75 0 45.25C304.4 412.9 296.2 416 288 416s-16.38-3.125-22.62-9.375L160 301.3L54.63 406.6C48.38 412.9 40.19 416 32 416S15.63 412.9 9.375 406.6c-12.5-12.5-12.5-32.75 0-45.25l105.4-105.4L9.375 150.6c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0L160 210.8l105.4-105.4c12.5-12.5 32.75-12.5 45.25 0s12.5 32.75 0 45.25l-105.4 105.4L310.6 361.4z\"><\/path><\/svg>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t","protected":false},"excerpt":{"rendered":"<p>En route vers Nantes pour un gros week-end en Nationale 1 jeunes ! L&rsquo;\u00e9quipe joue le samedi \u00e0 16h contre Nantes et le lendemain \u00e0 9h30 contre Rennes. Les adversaires sont forts et il va falloir beaucoup d&rsquo;\u00e9nergie!<\/p>\n","protected":false},"author":1,"featured_media":4289,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[30],"class_list":["post-6841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interclubs","tag-interclubs-jeunes"],"jetpack_featured_media_url":"https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png","uagb_featured_image_src":{"full":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png",371,494,false],"thumbnail":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs-113x150.png",113,150,true],"medium":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs-225x300.png",225,300,true],"medium_large":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png",371,494,false],"large":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png",371,494,false],"1536x1536":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png",371,494,false],"2048x2048":["https:\/\/bordeaux-echecs.fr\/wp-content\/uploads\/2022\/12\/jeunes_echecs.png",371,494,false]},"uagb_author_info":{"display_name":"Serge","author_link":"https:\/\/bordeaux-echecs.fr\/author\/bordeaux-echecs-serge\/"},"uagb_comment_info":1,"uagb_excerpt":"En route vers Nantes pour un gros week-end en Nationale 1 jeunes ! L&rsquo;\u00e9quipe joue le samedi \u00e0 16h contre Nantes et le lendemain \u00e0 9h30 contre Rennes. Les adversaires sont forts et il va falloir beaucoup d&rsquo;\u00e9nergie!","jetpack_shortlink":"https:\/\/wp.me\/p9pDgH-1Ml","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/posts\/6841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6841"}],"version-history":[{"count":4,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/posts\/6841\/revisions"}],"predecessor-version":[{"id":6851,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/posts\/6841\/revisions\/6851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/media\/4289"}],"wp:attachment":[{"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bordeaux-echecs.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}